{"id":2802,"date":"2026-09-01T18:07:41","date_gmt":"2026-09-01T18:07:41","guid":{"rendered":"https:\/\/iies.usac.edu.gt\/?p=2802"},"modified":"2026-09-01T18:11:26","modified_gmt":"2026-09-01T18:11:26","slug":"boletin-economia-al-dia-no-8-agosto-2026","status":"publish","type":"post","link":"https:\/\/iies.usac.edu.gt\/index.php\/2026\/09\/01\/boletin-economia-al-dia-no-8-agosto-2026\/","title":{"rendered":"Bolet\u00edn \u00abEconom\u00eda al d\u00eda\u00bb No. 8 agosto 2026"},"content":{"rendered":"\n<h3 class=\"wp-block-heading has-text-align-center\"><strong>La desvirtuaci\u00f3n de las exenciones tributarias y el papel del populismo pol\u00edtico<\/strong><\/h3>\n\n\n\n<p class=\"has-text-align-right\"><em>Autor: Dr. Edgar A. Marroqu\u00edn L\u00f3pez<\/em><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"has-white-background-color has-background\">El gasto tributario es un concepto fiscal que se especializa en los temas de exoneraciones, exenciones y deducciones o tratamientos tributarios especiales; por lo tanto, su existencia o configuraci\u00f3n es nutrida por actos o actividades identificadas con el denominador com\u00fan de no aportar y, por lo tanto, reducir los ingresos fiscales tributarios. Consecuentemente, toda reducci\u00f3n, exoneraci\u00f3n, deducci\u00f3n, tratamiento preferencial, o cualquier concepto similar, estar\u00eda, a nuestro juicio, en la \u00f3rbita del gasto tributario, en un sentido amplio y m\u00e1s realista.<\/p>\n\n\n\n<p class=\"has-luminous-vivid-amber-to-luminous-vivid-orange-gradient-background has-background\">El gasto tributario es el beneficio fiscal que el Estado otorga a determinadas actividades, empresas o personas por realizar determinadas actividades y por cumplir determinadas condiciones que las hacen aptas para este beneficio. Sin embargo, este beneficio es equivalente a un sacrificio fiscal para el Estado ya que son ingresos tributarios que este deja de percibir por fomentar, apadrinar o estimular actividades econ\u00f3micas y sociales que, si bien muchas son necesarias y funcionales, muchas otras en la pr\u00e1ctica no son merecedoras de tales beneficios, o los beneficios sociales y econ\u00f3micos de sus actividades que los calificaron para el beneficio fiscal, son m\u00ednimos o no son los ofrecidos o esperados.<\/p>\n\n\n\n<p class=\"has-white-background-color has-background\">La raz\u00f3n estatal principal de privarse de esos ingresos tributarios, identificados como gasto tributario, es para promover pol\u00edticas sociales y actividades econ\u00f3mico sociales promotoras de desarrollo econ\u00f3mico y bienestar de la poblaci\u00f3n.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/iies.usac.edu.gt\/wp-content\/uploads\/2026\/09\/Boletin-Economia-al-dia-No.-8-agosto-2026.png\" alt=\"\" class=\"wp-image-2804\" width=\"425\" height=\"555\" srcset=\"https:\/\/iies.usac.edu.gt\/wp-content\/uploads\/2026\/09\/Boletin-Economia-al-dia-No.-8-agosto-2026.png 567w, https:\/\/iies.usac.edu.gt\/wp-content\/uploads\/2026\/09\/Boletin-Economia-al-dia-No.-8-agosto-2026-230x300.png 230w\" sizes=\"(max-width: 425px) 100vw, 425px\" \/><\/figure><\/div>\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-vivid-red-background-color has-background wp-element-button\" href=\"https:\/\/iies.usac.edu.gt\/wp-content\/uploads\/2026\/09\/Boletin-Economia-al-dia-No.-8-agosto-2026.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Descargar Bolet\u00edn en PDF<\/a><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La desvirtuaci\u00f3n de las exenciones tributarias y el papel del<br \/>\npopulismo pol\u00edtico. Autor: Dr. Edgar A. Marroqu\u00edn L\u00f3pez. <\/p>\n","protected":false},"author":2,"featured_media":2807,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[43,1],"tags":[],"_links":{"self":[{"href":"https:\/\/iies.usac.edu.gt\/index.php\/wp-json\/wp\/v2\/posts\/2802"}],"collection":[{"href":"https:\/\/iies.usac.edu.gt\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/iies.usac.edu.gt\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/iies.usac.edu.gt\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/iies.usac.edu.gt\/index.php\/wp-json\/wp\/v2\/comments?post=2802"}],"version-history":[{"count":1,"href":"https:\/\/iies.usac.edu.gt\/index.php\/wp-json\/wp\/v2\/posts\/2802\/revisions"}],"predecessor-version":[{"id":2806,"href":"https:\/\/iies.usac.edu.gt\/index.php\/wp-json\/wp\/v2\/posts\/2802\/revisions\/2806"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/iies.usac.edu.gt\/index.php\/wp-json\/wp\/v2\/media\/2807"}],"wp:attachment":[{"href":"https:\/\/iies.usac.edu.gt\/index.php\/wp-json\/wp\/v2\/media?parent=2802"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/iies.usac.edu.gt\/index.php\/wp-json\/wp\/v2\/categories?post=2802"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/iies.usac.edu.gt\/index.php\/wp-json\/wp\/v2\/tags?post=2802"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}